{"id":44816,"date":"2024-01-24T10:29:38","date_gmt":"2024-01-24T15:29:38","guid":{"rendered":"https:\/\/www.simonssearchlight.org\/processo-de-pesquisa\/disturbios-geneticos-que-estudamos\/jarid2\/"},"modified":"2025-11-05T15:17:03","modified_gmt":"2025-11-05T20:17:03","slug":"jarid2","status":"publish","type":"page","link":"https:\/\/www.simonssearchlight.org\/pt-br\/processo-de-pesquisa\/disturbios-geneticos-que-estudamos\/jarid2\/","title":{"rendered":"JARID2"},"content":{"rendered":"<p><span class=\"TextRun SCXW175557777 BCX0\" lang=\"EN\" data-contrast=\"auto\"><br \/>\n  <span class=\"NormalTextRun SCXW175557777 BCX0\">As informa\u00e7\u00f5es para este resumo da <\/span><br \/>\n<\/span><strong><br \/>\n  <span class=\"TextRun MacChromeBold SCXW175557777 BCX0\" lang=\"EN\" data-contrast=\"auto\"><br \/>\n    <span class=\"NormalTextRun SCXW175557777 BCX0\">S\u00edndrome relacionada ao <span class=\"notranslate\">JARID2<\/span><\/span><br \/>\n  <\/span><br \/>\n<\/strong><span class=\"TextRun SCXW175557777 BCX0\" lang=\"EN\" data-contrast=\"auto\" xml:lang=\"EN\"><span class=\"NormalTextRun SCXW175557777 BCX0\">  vem de publica\u00e7\u00f5es de pesquisa. N\u00e3o se trata de substituir a orienta\u00e7\u00e3o m\u00e9dica. <\/span><\/span><span class=\"EOP SCXW175557777 BCX0\" data-ccp-props=\"{\"201341983\":0,\"335559740\":240}\"> <\/span><\/p>\n<p><a href=\"https:\/\/www.simonssearchlight.org\/pt-br\/gene-guide\/sindrome-relacionada-ao-jarid2\/\" target=\"_blank\" rel=\"noopener\"><strong>Clique aqui para ver nosso guia completo do gene JARID2<\/strong><\/a><\/p>\n<p><span style=\"font-weight: 400;\">O Gene Guide on-line inclui mais informa\u00e7\u00f5es sobre o <span class=\"notranslate\">JARID2<\/span>, como a chance de ter outro filho com essa condi\u00e7\u00e3o, problemas de comportamento e desenvolvimento ligados \u00e0 s\u00edndrome relacionada ao <span class=\"notranslate\">JARID2<\/span> ou especialistas a serem considerados por pessoas com essa condi\u00e7\u00e3o. Compartilhe este recurso com os membros da fam\u00edlia ou com seus provedores cl\u00ednicos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As informa\u00e7\u00f5es para este resumo da S\u00edndrome relacionada ao JARID2 vem de publica\u00e7\u00f5es de pesquisa. N\u00e3o se trata de substituir a orienta\u00e7\u00e3o m\u00e9dica. Clique aqui para ver nosso guia completo do gene JARID2 O Gene Guide on-line inclui mais informa\u00e7\u00f5es sobre o JARID2, como a chance de ter outro filho com essa condi\u00e7\u00e3o, problemas de [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"parent":43355,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-gene-card.php","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"acf":[],"_links":{"self":[{"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/pages\/44816"}],"collection":[{"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/comments?post=44816"}],"version-history":[{"count":2,"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/pages\/44816\/revisions"}],"predecessor-version":[{"id":63084,"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/pages\/44816\/revisions\/63084"}],"up":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/pages\/43355"}],"wp:attachment":[{"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/media?parent=44816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}