{"id":44707,"date":"2021-04-14T07:22:14","date_gmt":"2021-04-14T11:22:14","guid":{"rendered":"https:\/\/www.simonssearchlight.org\/processo-de-pesquisa\/disturbios-geneticos-que-estudamos\/delecao-de-16p11-2-distal\/"},"modified":"2026-04-06T15:32:21","modified_gmt":"2026-04-06T19:32:21","slug":"delecao-de-16p11-2-distal","status":"publish","type":"page","link":"https:\/\/www.simonssearchlight.org\/pt-br\/processo-de-pesquisa\/disturbios-geneticos-que-estudamos\/delecao-de-16p11-2-distal\/","title":{"rendered":"Dele\u00e7\u00e3o de 16p11.2 (distal)"},"content":{"rendered":"<p>Abaixo est\u00e1 um resumo da <strong>s\u00edndrome de dele\u00e7\u00e3o distal 16p11.2<\/strong> observada em publica\u00e7\u00f5es de pesquisa. N\u00e3o se trata de substituir a orienta\u00e7\u00e3o m\u00e9dica. <\/p>\n<p><a href=\"https:\/\/www.simonssearchlight.org\/es\/gene-guide\/delecion-distal-16p11-2\/\" target=\"_blank\" rel=\"noopener\"><strong>Clique aqui para ver nosso guia completo do gene de dele\u00e7\u00e3o distal 16p11.2<\/strong><\/a><\/p>\n<p>O Gene Guide on-line inclui mais informa\u00e7\u00f5es sobre a dele\u00e7\u00e3o distal 16p11.2, como a chance de ter outro filho com essa condi\u00e7\u00e3o, problemas de comportamento e desenvolvimento relacionados \u00e0 dele\u00e7\u00e3o distal 16p11.2 ou especialistas a serem considerados para pessoas com essa condi\u00e7\u00e3o. Compartilhe este recurso com os membros da fam\u00edlia ou com seus provedores cl\u00ednicos. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abaixo est\u00e1 um resumo da s\u00edndrome de dele\u00e7\u00e3o distal 16p11.2 observada em publica\u00e7\u00f5es de pesquisa. N\u00e3o se trata de substituir a orienta\u00e7\u00e3o m\u00e9dica. Clique aqui para ver nosso guia completo do gene de dele\u00e7\u00e3o distal 16p11.2 O Gene Guide on-line inclui mais informa\u00e7\u00f5es sobre a dele\u00e7\u00e3o distal 16p11.2, como a chance de ter outro filho [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"parent":43355,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-gene-card.php","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"acf":[],"_links":{"self":[{"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/pages\/44707"}],"collection":[{"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/comments?post=44707"}],"version-history":[{"count":5,"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/pages\/44707\/revisions"}],"predecessor-version":[{"id":73815,"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/pages\/44707\/revisions\/73815"}],"up":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/pages\/43355"}],"wp:attachment":[{"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/media?parent=44707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}