{"id":44136,"date":"2019-10-14T15:40:45","date_gmt":"2019-10-14T19:40:45","guid":{"rendered":"https:\/\/www.simonssearchlight.org\/44136-2\/"},"modified":"2024-03-21T15:18:51","modified_gmt":"2024-03-21T19:18:51","slug":"44136-2","status":"publish","type":"page","link":"https:\/\/www.simonssearchlight.org\/pt-br\/processo-de-pesquisa\/disturbios-geneticos-que-estudamos\/scn2a-2\/44136-2\/","title":{"rendered":""},"content":{"rendered":"<h2><strong>Variedade de muta\u00e7\u00f5es gen\u00e9ticas associadas \u00e0 defici\u00eancia intelectual espor\u00e1dica n\u00e3o sindr\u00f4mica grave: um estudo de sequenciamento do exoma<\/strong><\/h2>\n<p>Artigo original da pesquisa de Rauch <em>et al.<\/em> (2012).<\/p>\n<p>Leia o resumo <a href=\"http:\/\/www.ncbi.nlm.nih.gov\/pubmed\/23020937\">aqui<\/a>.<\/p>\n<p>O gene SCN2A desempenha um papel importante no desenvolvimento do c\u00e9rebro. Altera\u00e7\u00f5es nesse gene foram anteriormente associadas a dist\u00farbios convulsivos e diferen\u00e7as intelectuais significativas. Nesse estudo, as crian\u00e7as com altera\u00e7\u00f5es no gene SCN2A n\u00e3o apresentavam dist\u00farbios convulsivos. Em vez disso, essas crian\u00e7as tinham diferen\u00e7as intelectuais, problemas de comportamento e diferen\u00e7as sutis em suas caracter\u00edsticas faciais. Uma crian\u00e7a com uma altera\u00e7\u00e3o no SCN2A tamb\u00e9m apresentava algumas das caracter\u00edsticas do autismo. As altera\u00e7\u00f5es nesse gene n\u00e3o s\u00e3o herdadas com frequ\u00eancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Variedade de muta\u00e7\u00f5es gen\u00e9ticas associadas \u00e0 defici\u00eancia intelectual espor\u00e1dica n\u00e3o sindr\u00f4mica grave: um estudo de sequenciamento do exoma Artigo original da pesquisa de Rauch et al. (2012). Leia o resumo aqui. O gene SCN2A desempenha um papel importante no desenvolvimento do c\u00e9rebro. Altera\u00e7\u00f5es nesse gene foram anteriormente associadas a dist\u00farbios convulsivos e diferen\u00e7as intelectuais significativas. [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"parent":77101,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"acf":[],"_links":{"self":[{"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/pages\/44136"}],"collection":[{"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/comments?post=44136"}],"version-history":[{"count":1,"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/pages\/44136\/revisions"}],"predecessor-version":[{"id":44145,"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/pages\/44136\/revisions\/44145"}],"up":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/pages\/77101"}],"wp:attachment":[{"href":"https:\/\/www.simonssearchlight.org\/pt-br\/wp-json\/wp\/v2\/media?parent=44136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}