{"id":74858,"date":"2026-01-08T09:59:14","date_gmt":"2026-01-08T14:59:14","guid":{"rendered":"https:\/\/www.simonssearchlight.org\/2026\/01\/08\/simons-searchlight-2025-un-anno-in-rassegna\/"},"modified":"2026-01-08T10:06:53","modified_gmt":"2026-01-08T15:06:53","slug":"simons-searchlight-2025-un-anno-in-rassegna","status":"publish","type":"post","link":"https:\/\/www.simonssearchlight.org\/it\/2026\/01\/08\/simons-searchlight-2025-un-anno-in-rassegna\/","title":{"rendered":"Simons Searchlight 2025: Un anno in rassegna"},"content":{"rendered":"<h4>Nel 2025, la comunit\u00e0 <span class=\"notranslate\">Simons Searchlight<\/span> ha continuato a crescere, a connettersi e a portare avanti una ricerca significativa. Grazie all&#8217;impegno di famiglie, sostenitori e ricercatori di tutto il mondo, quest&#8217;anno ha portato nuova partecipazione, dati pi\u00f9 approfonditi e un reale impatto scientifico. <\/h4>\n<p><strong>2025 per numeri:<\/strong><\/p>\n<ul>\n<li>Registrati <strong>1.930<\/strong> partecipanti con varianti genetiche<\/li>\n<li>Completato <strong>2.750<\/strong> indagini anamnestiche<\/li>\n<li>Completati altri <strong>15.315<\/strong> sondaggi di ricerca<\/li>\n<li>Ha generato <strong>279<\/strong> rapporti trimestrali su 73 comunit\u00e0 genetiche<\/li>\n<li>Ha permesso di realizzare <strong>26<\/strong> pubblicazioni peer-reviewed utilizzando i dati di <span class=\"notranslate\">Simons Searchlight<\/span><\/li>\n<li>Ha ricevuto <strong>198<\/strong> richieste di dati e campioni biologici da parte di ricercatori.<\/li>\n<li>Raccolta di <strong>288<\/strong> campioni di sangue per la ricerca<\/li>\n<li>Ha esaminato <strong>1.250<\/strong> referti di test genetici<\/li>\n<li>Creazione di <strong>58<\/strong> guide alle condizioni genetiche basate sull&#8217;evidenza<\/li>\n<li>Registrati <strong>470<\/strong> partecipanti che non parlano inglese<\/li>\n<li>Rispondere a pi\u00f9 di <strong>9.500<\/strong> email di partecipanti<\/li>\n<li>Ricevuto un numero record di <strong>250<\/strong> domande di partecipazione al Comitato Consultivo Comunitario<\/li>\n<li>Ha partecipato a <strong>54<\/strong> conferenze di persona e virtuali<\/li>\n<li>Pubblicati <strong>250<\/strong> post sui social media per condividere ricerche e risorse<\/li>\n<\/ul>\n<p>Siamo profondamente grati a tutte le famiglie, i ricercatori e i partner che hanno reso possibile questo progresso. La partecipazione continua di anno in anno aiuta a creare dati potenti e a lungo termine che catturano le pietre miliari e i cambiamenti, informano le cure cliniche e gettano le basi per i trattamenti futuri. <strong>Siamo entusiasti di continuare a progredire insieme nel 2026<\/strong>. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-74846 size-large\" src=\"https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2026\/01\/08045632\/2025-grid-final-1024x1024.png\" alt=\"\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2026\/01\/08045632\/2025-grid-final-1024x1024.png 1024w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2026\/01\/08045632\/2025-grid-final-300x300.png 300w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2026\/01\/08045632\/2025-grid-final-150x150.png 150w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2026\/01\/08045632\/2025-grid-final-768x768.png 768w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2026\/01\/08045632\/2025-grid-final-1536x1536.png 1536w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2026\/01\/08045632\/2025-grid-final-2048x2048.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siamo grati a tutte le famiglie, i ricercatori e i partner che hanno reso possibile questo progresso.<\/p>\n","protected":false},"author":18,"featured_media":59069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[539,538],"tags":[],"class_list":["post-74858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-annuncio","category-dati"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.simonssearchlight.org\/it\/wp-json\/wp\/v2\/posts\/74858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.simonssearchlight.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simonssearchlight.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/it\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/it\/wp-json\/wp\/v2\/comments?post=74858"}],"version-history":[{"count":4,"href":"https:\/\/www.simonssearchlight.org\/it\/wp-json\/wp\/v2\/posts\/74858\/revisions"}],"predecessor-version":[{"id":74887,"href":"https:\/\/www.simonssearchlight.org\/it\/wp-json\/wp\/v2\/posts\/74858\/revisions\/74887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/it\/wp-json\/wp\/v2\/media\/59069"}],"wp:attachment":[{"href":"https:\/\/www.simonssearchlight.org\/it\/wp-json\/wp\/v2\/media?parent=74858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/it\/wp-json\/wp\/v2\/categories?post=74858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/it\/wp-json\/wp\/v2\/tags?post=74858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}