{"id":39860,"date":"2023-01-09T15:38:31","date_gmt":"2023-01-09T20:38:31","guid":{"rendered":"https:\/\/www.simonssearchlight.org\/2023\/01\/09\/des-chercheurs-utilisent-les-donnees-de-simons-searchlight-pour-faire-avancer-la-recherche-scientifique\/"},"modified":"2024-01-29T10:01:43","modified_gmt":"2024-01-29T15:01:43","slug":"des-chercheurs-utilisent-les-donnees-de-simons-searchlight-pour-faire-avancer-la-recherche-scientifique","status":"publish","type":"post","link":"https:\/\/www.simonssearchlight.org\/fr\/2023\/01\/09\/des-chercheurs-utilisent-les-donnees-de-simons-searchlight-pour-faire-avancer-la-recherche-scientifique\/","title":{"rendered":"Des chercheurs utilisent les donn\u00e9es de Simons Searchlight pour faire avancer la recherche scientifique"},"content":{"rendered":"<div class=\"group w-full text-gray-800 dark:text-gray-100 border-b border-black\/10 dark:border-gray-900\/50 bg-gray-50 dark:bg-[#444654]\">\n<div class=\"flex p-4 gap-4 text-base md:gap-6 md:max-w-2xl lg:max-w-xl xl:max-w-3xl md:py-6 lg:px-0 m-auto\">\n<div class=\"relative flex w-[calc(100%-50px)] flex-col gap-1 md:gap-3 lg:w-[calc(100%-115px)]\">\n<div class=\"flex flex-grow flex-col gap-3\">\n<div class=\"min-h-[20px] flex flex-col items-start gap-4 whitespace-pre-wrap break-words\">\n<div class=\"markdown prose w-full break-words dark:prose-invert light\">\n<p>Les chercheurs qui utilisent les donn\u00e9es de <span class=\"notranslate\">Simons Searchlight<\/span> soulignent le r\u00f4le cl\u00e9 des familles comme la v\u00f4tre dans la r\u00e9alisation d&#8217;avanc\u00e9es significatives dans le domaine scientifique. L&#8217;\u00e9tude de votre maladie g\u00e9n\u00e9tique rare du d\u00e9veloppement neurologique a un impact durable sur l&#8217;avenir de la recherche.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p><iframe loading=\"lazy\" title=\"Lecteur vid\u00e9o YouTube\" src=\"https:\/\/www.youtube.com\/embed\/JNkRmamFpWU\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00e9tude de votre trouble g\u00e9n\u00e9tique du d\u00e9veloppement neurologique a un impact durable sur l&#8217;avenir de la recherche.<\/p>\n","protected":false},"author":18,"featured_media":39753,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[193],"tags":[],"class_list":["post-39860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-video-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts\/39860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/comments?post=39860"}],"version-history":[{"count":1,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts\/39860\/revisions"}],"predecessor-version":[{"id":39869,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts\/39860\/revisions\/39869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/media\/39753"}],"wp:attachment":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/media?parent=39860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/categories?post=39860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/tags?post=39860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}