{"id":39838,"date":"2023-02-09T06:00:02","date_gmt":"2023-02-09T11:00:02","guid":{"rendered":"https:\/\/www.simonssearchlight.org\/2023\/02\/09\/lhistoire-demma-vivre-avec-la-mand\/"},"modified":"2024-01-29T10:01:41","modified_gmt":"2024-01-29T15:01:41","slug":"lhistoire-demma-vivre-avec-la-mand","status":"publish","type":"post","link":"https:\/\/www.simonssearchlight.org\/fr\/2023\/02\/09\/lhistoire-demma-vivre-avec-la-mand\/","title":{"rendered":"L&#8217;histoire d&#8217;Emma Vivre avec la MAND"},"content":{"rendered":"<h3 class=\"p1\"><b>Comment est votre famille ?<\/b><\/h3>\n<p class=\"p2\">Je pense que nous sommes assez normaux&#8230; nous aimons la musique, l&#8217;art et l&#8217;activit\u00e9 physique. Mes filles sont danseuses et gymnastes.<\/p>\n<h3 class=\"p1\"><b>Que faites-vous pour vous amuser ?<\/b><\/h3>\n<p class=\"p2\">Nous nous d\u00e9pla\u00e7ons \u00e0 v\u00e9lo et en scooter. Nous aimons aussi aller au cin\u00e9ma, dans les librairies ou au parc de trampolines.<\/p>\n<h3 class=\"p1\"><b>Parlez-nous de la plus grande difficult\u00e9 \u00e0 laquelle vous \u00eates confront\u00e9.<\/b><\/h3>\n<p class=\"p2\">Notre plus grande difficult\u00e9 est d&#8217;aider Emma \u00e0 s&#8217;autor\u00e9guler. Nous nous effor\u00e7ons donc toujours de trouver des solutions qui l&#8217;aident sur le moment, mais aussi de lui apprendre \u00e0 utiliser ses outils pour l&#8217;aider lorsque je ne suis pas l\u00e0 pour lui rappeler de respirer.<\/p>\n<h3 class=\"p1\"><b>Qu&#8217;est-ce qui vous motive \u00e0 participer \u00e0 la recherche ?  <\/b><\/h3>\n<p class=\"p2\">Notre histoire est un peu diff\u00e9rente de celle de beaucoup d&#8217;autres 2qtie&#8230; Emma a une mutation et elle est la seule \u00e0 avoir cette variante, il a donc \u00e9t\u00e9 tr\u00e8s difficile pour ses m\u00e9decins de la diagnostiquer. L&#8217;\u00e9quipe de g\u00e9n\u00e9tique de Stanford, bien qu&#8217;elle soit formidable, n&#8217;a d\u00e9couvert le diagnostic qu&#8217;\u00e0 l&#8217;\u00e2ge de 7 ans. Emma suivait d\u00e9j\u00e0 des programmes d&#8217;intervention pr\u00e9coce pour l&#8217;orthophonie et l&#8217;ergoth\u00e9rapie, mais nous n&#8217;en connaissions pas la cause jusqu&#8217;\u00e0 ce qu&#8217;elle re\u00e7oive son diagnostic et j&#8217;ai d\u00fb insister aupr\u00e8s de certains de ses m\u00e9decins pour qu&#8217;ils continuent. Un de ses m\u00e9decins m&#8217;a dit d&#8217;abandonner, que je ne conna\u00eetrais jamais la r\u00e9ponse. Parce que cette maladie est tr\u00e8s rare et qu&#8217;il n&#8217;y a pas beaucoup d&#8217;informations disponibles, la recherche est tr\u00e8s importante pour tous les enfants atteints de cette maladie, mais aussi pour ceux qui pourraient se trouver dans une situation similaire \u00e0 celle d&#8217;Emma.<\/p>\n<h3 class=\"p1\"><b>En quoi pensez-vous aider <span class=\"notranslate\">Simons Searchlight<\/span> \u00e0 en savoir plus sur les changements g\u00e9n\u00e9tiques rares ?<\/b><\/h3>\n<p class=\"p2\">Toute information partag\u00e9e peut \u00eatre utilis\u00e9e pour aider les autres.<\/p>\n<h3 class=\"p1\"><b>Quelle est la question \u00e0 laquelle vous souhaiteriez que les chercheurs puissent r\u00e9pondre au sujet de ce changement g\u00e9n\u00e9tique ?<\/b><\/h3>\n<p class=\"p2\">J&#8217;aimerais conna\u00eetre l&#8217;\u00e9tendue de la responsabilit\u00e9 du g\u00e8ne MBD5 et tous les d\u00e9fis possibles auxquels nous pourrions \u00eatre confront\u00e9s.<\/p>\n<h3 class=\"p1\"><b>Qu&#8217;avez-vous appris d&#8217;autres familles sur votre maladie g\u00e9n\u00e9tique ou celle de votre enfant ?<\/b><\/h3>\n<p class=\"p2\">Chacun est tellement diff\u00e9rent, mais dans l&#8217;ensemble, j&#8217;ai appris \u00e0 quel point les 2qties r\u00e9pandent la joie et l&#8217;amour.<\/p>\n<h3 class=\"p1\"><b>Si vous pouviez donner un conseil \u00e0 une personne r\u00e9cemment diagnostiqu\u00e9e comme ayant un changement g\u00e9n\u00e9tique dans votre famille, quel serait-il ?<\/b><\/h3>\n<p class=\"p2\">La routine, c&#8217;est tout ! Et soyez aussi analytique que possible. Il existe des solutions qui vous aideront beaucoup, il vous suffit de trouver ce qui convient \u00e0 votre famille. De plus, m\u00eame si les progr\u00e8s semblent lents, ils y parviendront et vous \u00e9prouverez beaucoup de joie \u00e0 les voir surmonter leurs difficult\u00e9s. J&#8217;ai pleur\u00e9 la premi\u00e8re fois qu&#8217;Emma a utilis\u00e9 des ciseaux normaux. Une chose \u00e0 laquelle je n&#8217;ai pas r\u00e9fl\u00e9chi \u00e0 deux fois avec ma fille a\u00een\u00e9e. Il y a tant de beaux moments comme celui-l\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment est votre famille ? Je pense que nous sommes assez normaux&#8230; nous aimons la musique, l&#8217;art et l&#8217;activit\u00e9 physique. Mes filles sont danseuses et gymnastes. Que faites-vous pour vous amuser ? Nous nous d\u00e9pla\u00e7ons \u00e0 v\u00e9lo et en scooter. Nous aimons aussi aller au cin\u00e9ma, dans les librairies ou au parc de trampolines. Parlez-nous [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":39846,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[189],"tags":[],"class_list":["post-39838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-histoire-de-famille"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts\/39838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/comments?post=39838"}],"version-history":[{"count":1,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts\/39838\/revisions"}],"predecessor-version":[{"id":39850,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts\/39838\/revisions\/39850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/media\/39846"}],"wp:attachment":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/media?parent=39838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/categories?post=39838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/tags?post=39838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}