{"id":39796,"date":"2022-10-28T14:46:44","date_gmt":"2022-10-28T18:46:44","guid":{"rendered":"https:\/\/www.simonssearchlight.org\/2022\/10\/28\/opportunite-de-recherche-externe-facematch\/"},"modified":"2024-01-29T10:01:37","modified_gmt":"2024-01-29T15:01:37","slug":"opportunite-de-recherche-externe-facematch","status":"publish","type":"post","link":"https:\/\/www.simonssearchlight.org\/fr\/2022\/10\/28\/opportunite-de-recherche-externe-facematch\/","title":{"rendered":"Opportunit\u00e9 de recherche externe : FaceMatch"},"content":{"rendered":"<h5>FaceMatch utilise la vision artificielle pour am\u00e9liorer le diagnostic.<\/h5>\n<p>FaceMatch est une plateforme qui aide les parents et les m\u00e9decins \u00e0 contribuer \u00e0 une base de donn\u00e9es internationale s\u00e9curis\u00e9e d&#8217;images d&#8217;enfants diagnostiqu\u00e9s et non diagnostiqu\u00e9s dans le monde entier. FaceMatch permet de comparer des images faciales et des caract\u00e9ristiques cliniquement document\u00e9es afin de trouver un diagnostic \u00e0 l&#8217;aide de l&#8217;intelligence artificielle. Un utilisateur peut t\u00e9l\u00e9charger une image de face et de profil du visage de son enfant dans la biblioth\u00e8que, et le logiciel d\u00e9terminera si l&#8217;enfant pr\u00e9sente une correspondance faciale \u00e9troite avec d&#8217;autres enfants de la base de donn\u00e9es. Les parents d&#8217;enfants sont encourag\u00e9s \u00e0 t\u00e9l\u00e9charger des images de leur enfant diagnostiqu\u00e9 \u00e0 diff\u00e9rents \u00e2ges sur le site de recrutement s\u00e9curis\u00e9 FaceMatch, approuv\u00e9 sur le plan \u00e9thique.<\/p>\n<p><em>*Cette \u00e9tude n&#8217;est pas affili\u00e9e \u00e0 <span class=\"notranslate\">Simons Searchlight<\/span>.<\/em><\/p>\n<p><a href=\"https:\/\/nam12.safelinks.protection.outlook.com\/?url=https%3A%2F%2Ffacematch.org.au%2Fhome&amp;data=05%7C01%7Ckesinger%40geisinger.edu%7Cf4be32a840cd4001428d08dab5f0f601%7C37d46c567c664402a16055c2313b910d%7C0%7C0%7C638022343771046773%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C3000%7C%7C%7C&amp;sdata=2ZI8kCfpy0244qTkXLAzu6FZ%2BsrjrU%2BFkNMmbSr3w9Q%3D&amp;reserved=0\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/nam12.safelinks.protection.outlook.com\/?url%3Dhttps%253A%252F%252Ffacematch.org.au%252Fhome%26data%3D05%257C01%257Ckesinger%2540geisinger.edu%257Cf4be32a840cd4001428d08dab5f0f601%257C37d46c567c664402a16055c2313b910d%257C0%257C0%257C638022343771046773%257CUnknown%257CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%253D%257C3000%257C%257C%257C%26sdata%3D2ZI8kCfpy0244qTkXLAzu6FZ%252BsrjrU%252BFkNMmbSr3w9Q%253D%26reserved%3D0&amp;source=gmail&amp;ust=1666801357127000&amp;usg=AOvVaw1tDS82MA0Bk-xOSymalHYJ\">Visitez le site web FaceMatch pour plus d&#8217;informations<\/a><\/p>\n<p><a href=\"https:\/\/www.simonssearchlight.org\/2022\/10\/24\/research-opportunity-facematch\/facematch\/\" rel=\"attachment wp-att-13735\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13735 alignnone\" src=\"https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2022\/10\/24104333\/Facematch.png\" alt=\"\" width=\"820\" height=\"312\" srcset=\"https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2022\/10\/24104333\/Facematch.png 820w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2022\/10\/24104333\/Facematch-300x114.png 300w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2022\/10\/24104333\/Facematch-768x292.png 768w\" sizes=\"auto, (max-width: 820px) 100vw, 820px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>FaceMatch utilise la vision artificielle pour am\u00e9liorer le diagnostic.  <\/p>\n","protected":false},"author":18,"featured_media":39812,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[197],"tags":[],"class_list":["post-39796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opportunite-de-recherche"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts\/39796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/comments?post=39796"}],"version-history":[{"count":1,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts\/39796\/revisions"}],"predecessor-version":[{"id":39816,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts\/39796\/revisions\/39816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/media\/39812"}],"wp:attachment":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/media?parent=39796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/categories?post=39796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/tags?post=39796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}