{"id":39695,"date":"2022-08-22T09:17:37","date_gmt":"2022-08-22T13:17:37","guid":{"rendered":"https:\/\/www.simonssearchlight.org\/2022\/08\/22\/rappel-de-lenquete-annuelle-sur-la-mise-a-jour-des-saisies\/"},"modified":"2024-01-29T10:01:31","modified_gmt":"2024-01-29T15:01:31","slug":"rappel-de-lenquete-annuelle-sur-la-mise-a-jour-des-saisies","status":"publish","type":"post","link":"https:\/\/www.simonssearchlight.org\/fr\/2022\/08\/22\/rappel-de-lenquete-annuelle-sur-la-mise-a-jour-des-saisies\/","title":{"rendered":"Rappel de l&#8217;enqu\u00eate annuelle sur la mise \u00e0 jour des saisies"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">\u00c0 ce stade, vous devriez avoir re\u00e7u une notification vous invitant \u00e0 r\u00e9pondre \u00e0 l&#8217;enqu\u00eate annuelle de mise \u00e0 jour des saisies sur votre tableau de bord de participant. Cette op\u00e9ration peut durer jusqu&#8217;\u00e0 30 minutes. Si le membre de votre famille ne souffre plus de crises d&#8217;\u00e9pilepsie, veuillez nous communiquer cette pr\u00e9cieuse information par le biais de l&#8217;enqu\u00eate. Cela ne prend qu&#8217;une minute. Cliquez sur le lien ci-dessous pour vous connecter \u00e0 votre tableau de bord. Sous &#8220;Toutes les t\u00e2ches&#8221; sur le c\u00f4t\u00e9 gauche, cliquez sur &#8220;Enqu\u00eate annuelle de mise \u00e0 jour des saisies&#8221; pour commencer l&#8217;enqu\u00eate.<\/span><\/p>\n<p><a href=\"https:\/\/bit.ly\/Simons_Searchlight_Dashboard\"><span style=\"font-weight: 400;\">Visitez votre tableau de bord<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compl\u00e9tez votre enqu\u00eate annuelle de mise \u00e0 jour des saisies.<\/p>\n","protected":false},"author":18,"featured_media":38814,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[188],"tags":[],"class_list":["post-39695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts\/39695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/comments?post=39695"}],"version-history":[{"count":1,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts\/39695\/revisions"}],"predecessor-version":[{"id":39701,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/posts\/39695\/revisions\/39701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/media\/38814"}],"wp:attachment":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/media?parent=39695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/categories?post=39695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/tags?post=39695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}