{"id":39156,"date":"2022-08-23T12:09:57","date_gmt":"2022-08-23T16:09:57","guid":{"rendered":"https:\/\/www.simonssearchlight.org\/publications\/"},"modified":"2026-03-24T06:18:01","modified_gmt":"2026-03-24T10:18:01","slug":"publications","status":"publish","type":"page","link":"https:\/\/www.simonssearchlight.org\/fr\/publications\/","title":{"rendered":"Publications"},"content":{"rendered":"<p><em>Date de r\u00e9vision : <span style=\"font-weight: 400;\">Mars<\/span> 2026<\/em><\/p>\n<p>Merci \u00e0 toutes les familles d&#8217;avoir particip\u00e9 \u00e0 <span class=\"notranslate\">Simons Searchlight<\/span>. Gr\u00e2ce \u00e0 votre participation, nous souhaitons aider les chercheurs et les g\u00e9n\u00e9ticiens du monde entier \u00e0 comprendre les maladies g\u00e9n\u00e9tiques qui vous affectent ou qui affectent votre famille.<\/p>\n<p>Les recherches men\u00e9es \u00e0 partir des donn\u00e9es de <span class=\"notranslate\">Simons Searchlight<\/span> ont donn\u00e9 lieu \u00e0 de nombreuses <span class=\"notranslate\">publications<\/span>. Ces documents sont soumis \u00e0 un processus d&#8217;examen par les pairs, dans le cadre duquel d&#8217;autres scientifiques \u00e9valuent et valident les recherches avant leur publication dans des revues scientifiques. En outre, certains r\u00e9sultats sont partag\u00e9s par le biais de pr\u00e9impressions, ce qui permet une diffusion rapide de l&#8217;information \u00e0 la communaut\u00e9 scientifique.<\/p>\n<p>De nombreuses <span class=\"notranslate\">publications<\/span> portent le nom de &#8220;Simons Variation in Individuals Project&#8221; (SimonsVIP), qui \u00e9tait le nom original de notre programme de recherche, d\u00e9sormais connu sous le nom de <span class=\"notranslate\">Simons Searchlight<\/span>.<\/p>\n<p>Les articles r\u00e9pertori\u00e9s sont organis\u00e9s du plus r\u00e9cent au plus ancien. Vous pouvez explorer les <span class=\"notranslate\">publications<\/span> par conditions g\u00e9n\u00e9tiques sp\u00e9cifiques en utilisant les cat\u00e9gories ci-dessous.<\/p>\n<p>En mars 2026, <span class=\"notranslate\">Simons Searchlight<\/span> a contribu\u00e9 \u00e0 <strong>139<\/strong><strong> <span class=\"notranslate\">publications<\/span> et pr\u00e9<span class=\"notranslate\">publications<\/span><\/strong>, et nous continuerons \u00e0 r\u00e9sumer les nouvelles <span class=\"notranslate\">publications<\/span>.<\/p>\n<p>Pour des raisons d&#8217;accessibilit\u00e9, la Fondation Simons encourage les chercheurs \u00e0 mettre leurs <span class=\"notranslate\">publications<\/span> en libre acc\u00e8s. Si vous ne pouvez pas acc\u00e9der \u00e0 un article de revue, nous vous recommandons de contacter le dernier auteur mentionn\u00e9 dans l&#8217;article pour lui demander une copie.<\/p>\n<p><strong>Comprendre les titres de r\u00e9f\u00e9rence des <span class=\"notranslate\">publications<\/span> :<\/strong><\/p>\n<p>-Le titre de l&#8217;article est suivi des d\u00e9tails de la publication, y compris le lieu et la date de publication.<br \/>\n&#8211; S&#8217;il y a plus de trois auteurs, nous utilisons &#8220;et al.&#8221; pour repr\u00e9senter les contributeurs suppl\u00e9mentaires.<br \/>\n&#8211; Les revues sont r\u00e9f\u00e9renc\u00e9es \u00e0 l&#8217;aide de noms abr\u00e9g\u00e9s.<\/p>\n<p><a href=\"https:\/\/www.simonssearchlight.org\/fr\/publications\/publications-page-image-2\/\" rel=\"attachment wp-att-13267\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-13267\" src=\"https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2022\/09\/13063004\/Publications-page-image-1024x345.png\" alt=\"\" width=\"1024\" height=\"345\" srcset=\"https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2022\/09\/13063004\/Publications-page-image-1024x345.png 1024w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2022\/09\/13063004\/Publications-page-image-300x101.png 300w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2022\/09\/13063004\/Publications-page-image-768x259.png 768w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2022\/09\/13063004\/Publications-page-image-1536x517.png 1536w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2022\/09\/13063004\/Publications-page-image-2048x690.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p><strong>Avertissement : <\/strong>veuillez noter que les articles publi\u00e9s sur medRxiv (prononc\u00e9 med-archive) ou bioRxiv (prononc\u00e9 bio-archive) ne font pas l&#8217;objet d&#8217;un examen par les pairs ou d&#8217;une r\u00e9vision avant d&#8217;\u00eatre publi\u00e9s en ligne. En revanche, tous les autres articles r\u00e9pertori\u00e9s ici ont fait l&#8217;objet d&#8217;un examen par des coll\u00e8gues chercheurs afin d&#8217;en garantir la qualit\u00e9 et l&#8217;exactitude. Bien que la publication sur medRxiv ou bioRxiv permette aux chercheurs de partager rapidement leurs r\u00e9sultats, les r\u00e9sultats finaux publi\u00e9s peuvent diff\u00e9rer apr\u00e8s avoir \u00e9t\u00e9 soumis \u00e0 un examen formel par des pairs en vue d&#8217;une publication dans une revue.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Date de r\u00e9vision : Mars 2026 Merci \u00e0 toutes les familles d&#8217;avoir particip\u00e9 \u00e0 Simons Searchlight. Gr\u00e2ce \u00e0 votre participation, nous souhaitons aider les chercheurs et les g\u00e9n\u00e9ticiens du monde entier \u00e0 comprendre les maladies g\u00e9n\u00e9tiques qui vous affectent ou qui affectent votre famille. Les recherches men\u00e9es \u00e0 partir des donn\u00e9es de Simons Searchlight ont [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-publications.php","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"acf":[],"_links":{"self":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/pages\/39156"}],"collection":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/comments?post=39156"}],"version-history":[{"count":20,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/pages\/39156\/revisions"}],"predecessor-version":[{"id":77961,"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/pages\/39156\/revisions\/77961"}],"wp:attachment":[{"href":"https:\/\/www.simonssearchlight.org\/fr\/wp-json\/wp\/v2\/media?parent=39156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}