{"id":77577,"date":"2026-02-27T13:47:47","date_gmt":"2026-02-27T18:47:47","guid":{"rendered":"https:\/\/www.simonssearchlight.org\/2026\/02\/27\/el-viaje-de-los-childers-con-sindrome-relacionado-con-ebf3-y-sindrome-relacionado-con-auts2\/"},"modified":"2026-03-02T11:41:33","modified_gmt":"2026-03-02T16:41:33","slug":"el-viaje-de-los-childers-con-sindrome-relacionado-con-ebf3-y-sindrome-relacionado-con-auts2","status":"publish","type":"post","link":"https:\/\/www.simonssearchlight.org\/es\/2026\/02\/27\/el-viaje-de-los-childers-con-sindrome-relacionado-con-ebf3-y-sindrome-relacionado-con-auts2\/","title":{"rendered":"El viaje de los Childers con s\u00edndrome relacionado con EBF3 y s\u00edndrome relacionado con AUTS2"},"content":{"rendered":"<h3>\u00bfC\u00f3mo es su familia?<\/h3>\n<p>Mi prometido y yo tenemos dos hijos, y tanto mi hijo como yo padecemos el trastorno HADDS, as\u00ed como el s\u00edndrome AUTS2, que son dos trastornos raros del desarrollo que vienen acompa\u00f1ados de un mont\u00f3n de afecciones m\u00e9dicas. Nuestra hija tiene 2 a\u00f1os y nuestro hijo 8, y ambos son la luz de nuestras vidas. Mi familia es muy extrovertida y aventurera, y nos encanta explorar nuevos lugares y vivir nuevas experiencias.  <\/p>\n<h3 dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwiKo7raoNyJAxXFK1kFHZOGOr4Q3ewLegQICRAW\" aria-label=\"Translated text: I am Toto's mother with a mutation in GENE NAA 15\"><strong>\u00bfQu\u00e9 hace para divertirse?<\/strong><\/h3>\n<p dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwiKo7raoNyJAxXFK1kFHZOGOr4Q3ewLegQICRAW\" aria-label=\"Translated text: I am Toto's mother with a mutation in GENE NAA 15\">Nos encanta ir de excursi\u00f3n y explorar nuevos lugares. Intentamos ir a Disneyworld todos los a\u00f1os si podemos, porque es nuestro lugar feliz y nuestros hijos pueden ser ni\u00f1os sin ser juzgados. <\/p>\n<h3 class=\"p1\"><b>H\u00e1blenos de la mayor dificultad a la que se enfrenta.<\/b><\/h3>\n<p>La mayor dificultad a la que se enfrenta nuestra familia son las personas que nos juzgan porque nuestra vida es muy diferente a la de otras familias. Tenemos muchas citas con el m\u00e9dico y con el terapeuta, y normalmente no disponemos del tiempo extra que tienen otras familias. Otra dificultad a la que nos enfrentamos es que no hay suficientes profesionales m\u00e9dicos que conozcan nuestros dos trastornos, por lo que hemos tenido que defenderlos ferozmente y educar a los m\u00e9dicos y al personal relacionado.  <\/p>\n<h3 class=\"p1\"><b><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16089 alignleft\" src=\"https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2023\/09\/11092158\/PEOPLE_man-loves-microscope-300x300.png\" alt=\"\" width=\"317\" height=\"317\" srcset=\"https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2023\/09\/11092158\/PEOPLE_man-loves-microscope-300x300.png 300w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2023\/09\/11092158\/PEOPLE_man-loves-microscope-1024x1024.png 1024w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2023\/09\/11092158\/PEOPLE_man-loves-microscope-150x150.png 150w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2023\/09\/11092158\/PEOPLE_man-loves-microscope-768x768.png 768w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2023\/09\/11092158\/PEOPLE_man-loves-microscope-1536x1536.png 1536w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2023\/09\/11092158\/PEOPLE_man-loves-microscope-2048x2048.png 2048w\" sizes=\"auto, (max-width: 317px) 100vw, 317px\" \/><\/b><\/h3>\n<h3 class=\"p1\">\u00bfQu\u00e9 le motiva a participar en la investigaci\u00f3n? \u00bfEn qu\u00e9 le ha ayudado participar en la investigaci\u00f3n?<\/h3>\n<p>Soy uno de los pocos adultos del mundo que tienen AUTS2 y s\u00edndrome HADDS, y creo que es muy importante participar en la investigaci\u00f3n para obtener m\u00e1s informaci\u00f3n sobre estos trastornos, para que haya mejores opciones de tratamiento y para que se conozcan mejor ambos trastornos. Ha sido \u00fatil porque ahora entendemos algunas cosas que antes no entend\u00edamos. <\/p>\n<h3 class=\"p1\">\u00bfC\u00f3mo cree que est\u00e1 ayudando a <span class=\"notranslate\">Simons Searchlight<\/span> a conocer mejor las alteraciones gen\u00e9ticas raras?<\/h3>\n<p>Creo que estamos ayudando a los investigadores a encontrar las causas de determinados s\u00edntomas de los trastornos y a aprender m\u00e1s sobre los cambios cerebrales y sobre c\u00f3mo pueden influir de forma tan diferente en cada persona, as\u00ed como sobre el hecho de que ambos s\u00edndromes son una gama y no todos experimentar\u00e1n las mismas cosas y algunos tendr\u00e1n m\u00e1s dificultades que otros, y esto ayuda a investigar para averiguar el porqu\u00e9 de lo que ocurre.<\/p>\n<h3 class=\"p1\"><b>\u00bfQu\u00e9 pregunta le gustar\u00eda que los investigadores pudieran responder sobre este cambio gen\u00e9tico?<\/b><\/h3>\n<p>Deseo saber por qu\u00e9 en la EBF3 el cerebelo es m\u00e1s peque\u00f1o de lo que deber\u00eda, y qu\u00e9 debemos esperar exactamente con ese hallazgo. Con el AUTS2, deseo concienciar m\u00e1s sobre ese trastorno, as\u00ed como por qu\u00e9 entra en juego la discapacidad intelectual y cu\u00e1l es su causa, si es que hay alguna. <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-15175 size-medium alignright\" src=\"https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2023\/05\/18092145\/PEOPLE_man-girl-step-hearts-300x300.png\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2023\/05\/18092145\/PEOPLE_man-girl-step-hearts-300x300.png 300w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2023\/05\/18092145\/PEOPLE_man-girl-step-hearts-1024x1024.png 1024w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2023\/05\/18092145\/PEOPLE_man-girl-step-hearts-150x150.png 150w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2023\/05\/18092145\/PEOPLE_man-girl-step-hearts-768x768.png 768w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2023\/05\/18092145\/PEOPLE_man-girl-step-hearts-1536x1536.png 1536w, https:\/\/cdn.simonssearchlight.org\/wp-content\/uploads\/2023\/05\/18092145\/PEOPLE_man-girl-step-hearts-2048x2048.png 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<h3 class=\"p1\">\u00bfQu\u00e9 ha aprendido de otras familias sobre su enfermedad gen\u00e9tica o la de su hijo?<\/h3>\n<p dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwiKo7raoNyJAxXFK1kFHZOGOr4Q3ewLegQICRAW\" aria-label=\"Translated text: That everything can be achieved with therapy, patience and love.\">Me he unido a una maravillosa comunidad de facebook para ambos trastornos y en esas comunidades he encontrado inclusi\u00f3n, aceptaci\u00f3n y un nivel m\u00e1s profundo de comprensi\u00f3n que no he encontrado en ning\u00fan otro sitio y estamos conectados con personas que simplemente lo entienden, sin tener que explicar cada peque\u00f1a cosa y simplificar las cosas. He aprendido que cada uno de nosotros es \u00fanico, pero que todos compartimos al menos algunas cosas en com\u00fan con ambos trastornos. <\/p>\n<h3 dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwiKo7raoNyJAxXFK1kFHZOGOr4Q3ewLegQICRAW\" aria-label=\"Translated text: That everything can be achieved with therapy, patience and love.\"><strong>Si pudiera dar un consejo a alguien a quien se le haya diagnosticado recientemente esta alteraci\u00f3n gen\u00e9tica, \u00bfcu\u00e1l ser\u00eda?<\/strong><\/h3>\n<p>Mi consejo ser\u00eda que no te subestimes ni subestimes a tu hijo porque las grandes cosas vienen con el conocimiento y el conocimiento es poder. Tambi\u00e9n dir\u00eda que, aunque a veces parezca sombr\u00edo, no lo es en absoluto, y que encuentres a tu pueblo y te apoyes en esas personas. <\/p>\n<h3 dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwiKo7raoNyJAxXFK1kFHZOGOr4Q3ewLegQICRAW\" aria-label=\"Translated text: That everything can be achieved with therapy, patience and love.\"><strong>\u00bfC\u00f3mo ha servido <span class=\"notranslate\">Simons Searchlight<\/span> de recurso para ti y tu familia?  <\/strong><\/h3>\n<p dir=\"ltr\" data-placeholder=\"Translation\" data-ved=\"2ahUKEwiKo7raoNyJAxXFK1kFHZOGOr4Q3ewLegQICRAW\" aria-label=\"Translated text: That everything can be achieved with therapy, patience and love.\">Ha sido incre\u00edble en cuanto a leer sobre distintos trastornos y sin duda est\u00e1 concienciando m\u00e1s sobre nuestros dos trastornos, cosa que me encanta ver.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descubre la inspiradora historia de los Childers.<\/p>\n","protected":false},"author":28,"featured_media":77573,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[96],"tags":[],"class_list":["post-77577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historia-de-una-familia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/posts\/77577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/comments?post=77577"}],"version-history":[{"count":1,"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/posts\/77577\/revisions"}],"predecessor-version":[{"id":77589,"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/posts\/77577\/revisions\/77589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/media\/77573"}],"wp:attachment":[{"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/media?parent=77577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/categories?post=77577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/tags?post=77577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}