{"id":19512,"date":"2023-05-18T12:04:58","date_gmt":"2023-05-18T16:04:58","guid":{"rendered":"https:\/\/www.simonssearchlight.org\/2023\/05\/18\/ya-estan-disponibles-los-resultados-de-la-nueva-encuesta-sobre-el-historial-de-incautaciones-de-simons-searchlight\/"},"modified":"2023-11-20T15:34:48","modified_gmt":"2023-11-20T20:34:48","slug":"ya-estan-disponibles-los-resultados-de-la-nueva-encuesta-sobre-el-historial-de-incautaciones-de-simons-searchlight","status":"publish","type":"post","link":"https:\/\/www.simonssearchlight.org\/es\/2023\/05\/18\/ya-estan-disponibles-los-resultados-de-la-nueva-encuesta-sobre-el-historial-de-incautaciones-de-simons-searchlight\/","title":{"rendered":"Ya est\u00e1n disponibles los resultados de la nueva encuesta sobre el historial de incautaciones de Simons Searchlight"},"content":{"rendered":"<h3><strong>Obtenga informaci\u00f3n importante sobre las convulsiones para su condici\u00f3n gen\u00e9tica: Ya est\u00e1n disponibles los resultados de la encuesta sobre el historial de convulsiones de <span class=\"notranslate\">Simons Searchlight<\/span>.<\/strong><\/h3>\n<p>Si ha sufrido convulsiones y ha informado de ellas en la encuesta <span class=\"notranslate\">Simons Searchlight<\/span> Seizure History desde 2021 hasta la actualidad, \u00a1ahora puede acceder a los resultados personalizados de la encuesta! Estos resultados contienen informaci\u00f3n crucial sobre su comunidad gen\u00e9tica y detalles sobre los tratamientos que se han probado y lo que cabe esperar en t\u00e9rminos de evoluci\u00f3n. Tambi\u00e9n puede imprimir esta informaci\u00f3n para sus archivos.<\/p>\n<p><strong>\u00bfQui\u00e9n tendr\u00e1 los resultados de la encuesta sobre incautaciones en su tablero de mandos?<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Si inform\u00f3 de convulsiones en la encuesta de historial de convulsiones, puede acceder a esta informaci\u00f3n en la secci\u00f3n \u00abTareas completadas\u00bb de su tablero de mandos. <\/span><a href=\"http:\/\/bit.ly\/Simons_Searchlight_Dashboard\"><br \/>\n  <span style=\"font-weight: 400;\">secci\u00f3n \u00abTareas completadas\u00bb de su panel de control<\/span><br \/>\n<\/a><span style=\"font-weight: 400;\">. Los resultados s\u00f3lo est\u00e1n disponibles para las familias que notifican convulsiones en comunidades gen\u00e9ticas con al menos 5 individuos con convulsiones.<\/span><\/p>\n<p><strong>Complete su encuesta sobre el historial de convulsiones<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Si a\u00fan no ha completado la encuesta sobre el historial de incautaciones, le animamos a que lo haga hoy mismo <\/span><a href=\"http:\/\/bit.ly\/Simons_Searchlight_Dashboard\"><br \/>\n  <span style=\"font-weight: 400;\">visitando su panel de control<\/span><br \/>\n<\/a><span style=\"font-weight: 400;\">\u00a1! Sus resultados se entregar\u00e1n al instante sin ning\u00fan retraso. No pierda esta valiosa oportunidad de conocer mejor su condici\u00f3n gen\u00e9tica.  <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Obtenga informaci\u00f3n importante sobre las convulsiones para su enfermedad gen\u00e9tica.<\/p>\n","protected":false},"author":18,"featured_media":17707,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[103,98],"tags":[],"class_list":["post-19512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-datos","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/posts\/19512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/comments?post=19512"}],"version-history":[{"count":1,"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/posts\/19512\/revisions"}],"predecessor-version":[{"id":19515,"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/posts\/19512\/revisions\/19515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/media\/17707"}],"wp:attachment":[{"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/media?parent=19512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/categories?post=19512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.simonssearchlight.org\/es\/wp-json\/wp\/v2\/tags?post=19512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}